{"id":229105,"date":"2026-06-27T15:31:00","date_gmt":"2026-06-27T10:01:00","guid":{"rendered":"https:\/\/newtelugunews.com\/te\/?p=229105"},"modified":"2026-06-27T09:32:38","modified_gmt":"2026-06-27T04:02:38","slug":"%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6","status":"publish","type":"post","link":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/","title":{"rendered":"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0c28\u0c4d\u0c2f\u0c42\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40: \u0c1a\u0c3f\u0c28\u0c4d\u0c28\u0c24\u0c28\u0c02\u0c32\u0c4b\u0c28\u0c47 \u0c05\u0c26\u0c4d\u0c2d\u0c41\u0c24\u0c2e\u0c48\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c28\u0c41 \u0c38\u0c3e\u0c27\u0c3f\u0c02\u0c1a\u0c3f, \u0c26\u0c47\u0c36\u0c35\u0c4d\u0c2f\u0c3e\u0c2a\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c05\u0c02\u0c26\u0c30\u0c3f \u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c3f\u0c28\u0c3f \u0c06\u0c15\u0c30\u0c4d\u0c37\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f. 11 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c21\u0c3f\u0c17\u0c4d\u0c30\u0c40, 21 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c2a\u0c40\u0c39\u0c46\u0c1a\u0c4d\u200c\u0c21\u0c40, 22 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c10\u0c10\u0c1f\u0c40 \u0c2a\u0c4d\u0c30\u0c4a\u0c2b\u0c46\u0c38\u0c30\u0c4d.. \u0c07\u0c32\u0c3e \u0c06\u0c2f\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c2a\u0c4d\u0c30\u0c2f\u0c3e\u0c23\u0c02 \u0c0e\u0c02\u0c24\u0c4b \u0c2e\u0c02\u0c26\u0c3f\u0c28\u0c3f \u0c05\u0c2c\u0c4d\u0c2c\u0c41\u0c30\u0c2a\u0c30\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c05\u0c2f\u0c3f\u0c24\u0c47, \u0c26\u0c41\u0c30\u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c35\u0c36\u0c3e\u0c24\u0c4d\u0c24\u0c41 \u0c05\u0c28\u0c3e\u0c30\u0c4b\u0c17\u0c4d\u0c2f \u0c15\u0c3e\u0c30\u0c23\u0c3e\u0c32 \u0c35\u0c32\u0c4d\u0c32 \u0c06\u0c2f\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d\u200c\u0c32\u0c4b \u0c0a\u0c39\u0c3f\u0c02\u0c1a\u0c28\u0c3f \u0c2e\u0c32\u0c41\u0c2a\u0c41\u0c32\u0c41 \u0c1a\u0c4b\u0c1f\u0c41\u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c06\u0c2f\u0c28 \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c02 (Law) \u0c05\u0c2d\u0c4d\u0c2f\u0c38\u0c3f\u0c38\u0c4d\u0c24\u0c42 \u0c15\u0c4a\u0c24\u0c4d\u0c24 \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c47 \u0c2a\u0c4d\u0c30\u0c2f\u0c24\u0c4d\u0c28\u0c02\u0c32\u0c4b \u0c09\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0c0e\u0c35\u0c30\u0c40 \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f?<br>1987 \u0c38\u0c46\u0c2a\u0c4d\u0c1f\u0c46\u0c02\u0c2c\u0c30\u0c4d 9\u0c28 \u0c2c\u0c40\u0c39\u0c3e\u0c30\u0c4d\u200c\u0c32\u0c4b \u0c1c\u0c28\u0c4d\u0c2e\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c24\u0c41\u0c32\u0c38\u0c3f, \u0c1a\u0c3f\u0c28\u0c4d\u0c28\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c47 \u0c05\u0c38\u0c3e\u0c27\u0c3e\u0c30\u0c23 \u0c24\u0c46\u0c32\u0c3f\u0c35\u0c3f\u0c24\u0c47\u0c1f\u0c32\u0c28\u0c41 \u0c2a\u0c4d\u0c30\u0c26\u0c30\u0c4d\u0c36\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9 \u0c0f\u0c33\u0c4d\u0c32 \u0c35\u0c2f\u0c38\u0c41\u0c32\u0c4b\u0c28\u0c47 \u0c2a\u0c3e\u0c20\u0c36\u0c3e\u0c32 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c28\u0c41 \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f \u0c1a\u0c47\u0c36\u0c3e\u0c30\u0c41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c41 \u0c2c\u0c40\u0c0e\u0c38\u0c4d\u0c38\u0c40 (B.Sc) \u0c21\u0c3f\u0c17\u0c4d\u0c30\u0c40\u0c28\u0c3f, 12 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c41 \u0c0e\u0c02\u0c0e\u0c38\u0c4d\u0c38\u0c40 (M.Sc) \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f \u0c1a\u0c47\u0c38\u0c3f \u0c05\u0c02\u0c26\u0c30\u0c3f\u0c28\u0c40 \u0c06\u0c36\u0c4d\u0c1a\u0c30\u0c4d\u0c2f\u0c2a\u0c30\u0c3f\u0c1a\u0c3e\u0c30\u0c41.<br>\u0c2d\u0c4c\u0c24\u0c3f\u0c15 \u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c02, \u0c17\u0c23\u0c3f\u0c24\u0c02\u0c32\u0c4b \u0c06\u0c2f\u0c28 \u0c1a\u0c42\u0c2a\u0c3f\u0c28 \u0c2a\u0c4d\u0c30\u0c24\u0c3f\u0c2d \u0c35\u0c32\u0c4d\u0c32 \u0c06\u0c2f\u0c28\u0c28\u0c41 \u0c26\u0c47\u0c36\u0c02\u0c32\u0c4b\u0c28\u0c3f &#8216;\u0c2f\u0c02\u0c17\u0c46\u0c38\u0c4d\u0c1f\u0c4d \u0c05\u0c15\u0c21\u0c2e\u0c3f\u0c15\u0c4d \u0c1f\u0c3e\u0c32\u0c46\u0c02\u0c1f\u0c4d&#8217;\u0c17\u0c3e \u0c17\u0c41\u0c30\u0c4d\u0c24\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0c2a\u0c40\u0c39\u0c46\u0c1a\u0c4d\u200c\u0c21\u0c40 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c10\u0c10\u0c1f\u0c40 \u0c2a\u0c4d\u0c30\u0c4a\u0c2b\u0c46\u0c38\u0c30\u0c4d\u200c\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02:<br>\u0c2e\u0c3e\u0c38\u0c4d\u0c1f\u0c30\u0c4d\u0c38\u0c4d \u0c2a\u0c42\u0c30\u0c4d\u0c24\u0c3f \u0c1a\u0c47\u0c38\u0c3f\u0c28 \u0c24\u0c30\u0c4d\u0c35\u0c3e\u0c24, \u0c07\u0c02\u0c21\u0c3f\u0c2f\u0c28\u0c4d \u0c07\u0c28\u0c4d\u200c\u0c38\u0c4d\u0c1f\u0c3f\u0c1f\u0c4d\u0c2f\u0c42\u0c1f\u0c4d \u0c06\u0c2b\u0c4d \u0c38\u0c48\u0c28\u0c4d\u0c38\u0c4d (IISc)\u0c32\u0c4b \u0c2a\u0c30\u0c3f\u0c36\u0c4b\u0c27\u0c28\u0c32\u0c41 \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. &#8216;\u0c1c\u0c28\u0c30\u0c32\u0c48\u0c1c\u0c47\u0c37\u0c28\u0c4d\u0c38\u0c4d \u0c06\u0c2b\u0c4d \u0c26\u0c3f \u0c15\u0c4d\u0c35\u0c3e\u0c02\u0c1f\u0c02 \u0c38\u0c46\u0c30\u0c4d\u0c1a\u0c4d \u0c05\u0c32\u0c4d\u0c17\u0c3e\u0c30\u0c3f\u0c25\u0c2e\u0c4d&#8217; \u0c05\u0c28\u0c47 \u0c05\u0c02\u0c36\u0c02\u0c2a\u0c48 \u0c2a\u0c30\u0c3f\u0c36\u0c4b\u0c27\u0c28 \u0c1a\u0c47\u0c38\u0c3f, \u0c15\u0c47\u0c35\u0c32\u0c02 21 \u0c0f\u0c33\u0c4d\u0c32 \u0c35\u0c2f\u0c38\u0c41\u0c32\u0c4b\u0c28\u0c47 \u0c21\u0c3e\u0c15\u0c4d\u0c1f\u0c30\u0c47\u0c1f\u0c4d (PhD) \u0c38\u0c3e\u0c27\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41. \u0c06 \u0c24\u0c30\u0c4d\u0c35\u0c3e\u0c24 2010\u0c32\u0c4b, \u0c05\u0c02\u0c1f\u0c47 \u0c24\u0c28 22\u0c35 \u0c0f\u0c1f \u0c10\u0c10\u0c1f\u0c40 \u0c2c\u0c3e\u0c02\u0c2c\u0c47\u0c32\u0c4b \u0c15\u0c3e\u0c02\u0c1f\u0c4d\u0c30\u0c3e\u0c15\u0c4d\u0c1f\u0c4d \u0c2a\u0c4d\u0c30\u0c4a\u0c2b\u0c46\u0c38\u0c30\u0c4d\u200c\u0c17\u0c3e \u0c28\u0c3f\u0c2f\u0c2e\u0c3f\u0c24\u0c41\u0c32\u0c2f\u0c4d\u0c2f\u0c3e\u0c30\u0c41. \u0c15\u0c4d\u0c35\u0c3e\u0c02\u0c1f\u0c02 \u0c15\u0c02\u0c2a\u0c4d\u0c2f\u0c42\u0c1f\u0c3f\u0c02\u0c17\u0c4d \u0c30\u0c02\u0c17\u0c02\u0c32\u0c4b \u0c2a\u0c4d\u0c30\u0c38\u0c3f\u0c26\u0c4d\u0c27 \u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c35\u0c47\u0c24\u0c4d\u0c24 \u0c32\u0c35\u0c4d \u0c17\u0c4d\u0c30\u0c4b\u0c35\u0c30\u0c4d\u200c\u0c24\u0c4b \u0c15\u0c32\u0c3f\u0c38\u0c3f \u0c06\u0c2f\u0c28 \u0c2a\u0c30\u0c3f\u0c36\u0c4b\u0c27\u0c28\u0c3e \u0c2a\u0c24\u0c4d\u0c30\u0c3e\u0c32\u0c28\u0c41 \u0c30\u0c42\u0c2a\u0c4a\u0c02\u0c26\u0c3f\u0c02\u0c1a\u0c3e\u0c30\u0c41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0c06\u0c30\u0c4b\u0c17\u0c4d\u0c2f \u0c38\u0c2e\u0c38\u0c4d\u0c2f\u0c32\u0c41 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c2e\u0c32\u0c41\u0c2a\u0c41:<br>2011\u0c32\u0c4b \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c28 \u0c24\u0c40\u0c35\u0c4d\u0c30\u0c2e\u0c48\u0c28 \u0c1c\u0c4d\u0c35\u0c30\u0c02, \u0c24\u0c26\u0c28\u0c02\u0c24\u0c30\u0c02 \u0c0f\u0c30\u0c4d\u0c2a\u0c21\u0c3f\u0c28 \u0c0e\u0c32\u0c30\u0c4d\u0c1c\u0c40 \u0c38\u0c2e\u0c38\u0c4d\u0c2f\u0c32\u0c41 \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d\u200c\u0c2a\u0c48 \u0c24\u0c40\u0c35\u0c4d\u0c30 \u0c2a\u0c4d\u0c30\u0c2d\u0c3e\u0c35\u0c02 \u0c1a\u0c42\u0c2a\u0c3e\u0c2f\u0c3f. \u0c06\u0c30\u0c4b\u0c17\u0c4d\u0c2f\u0c02 \u0c15\u0c4d\u0c37\u0c40\u0c23\u0c3f\u0c02\u0c1a\u0c21\u0c02\u0c24\u0c4b \u0c06\u0c2f\u0c28 \u0c2c\u0c4b\u0c27\u0c28, \u0c2a\u0c30\u0c3f\u0c36\u0c4b\u0c27\u0c28\u0c32\u0c28\u0c41 \u0c15\u0c4a\u0c28\u0c38\u0c3e\u0c17\u0c3f\u0c02\u0c1a\u0c32\u0c47\u0c15\u0c2a\u0c4b\u0c2f\u0c3e\u0c30\u0c41. 2013\u0c32\u0c4b \u0c38\u0c41\u0c26\u0c40\u0c30\u0c4d\u0c18 \u0c35\u0c48\u0c26\u0c4d\u0c2f \u0c38\u0c46\u0c32\u0c35\u0c41\u0c32\u0c2a\u0c48 \u0c35\u0c46\u0c33\u0c4d\u0c32\u0c3e\u0c32\u0c4d\u0c38\u0c3f \u0c35\u0c1a\u0c4d\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c38\u0c41\u0c2e\u0c3e\u0c30\u0c41 \u0c28\u0c3e\u0c32\u0c41\u0c17\u0c47\u0c33\u0c4d\u0c32 \u0c2a\u0c3e\u0c1f\u0c41 \u0c06\u0c2f\u0c28 \u0c05\u0c02\u0c26\u0c41\u0c2c\u0c3e\u0c1f\u0c41\u0c32\u0c4b \u0c32\u0c47\u0c15\u0c2a\u0c4b\u0c35\u0c21\u0c02\u0c24\u0c4b, 2019\u0c32\u0c4b \u0c10\u0c10\u0c1f\u0c40 \u0c2c\u0c3e\u0c02\u0c2c\u0c47 \u0c06\u0c2f\u0c28 \u0c15\u0c3e\u0c02\u0c1f\u0c4d\u0c30\u0c3e\u0c15\u0c4d\u0c1f\u0c4d \u0c12\u0c2a\u0c4d\u0c2a\u0c02\u0c26\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c2e\u0c41\u0c17\u0c3f\u0c02\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c06\u0c38\u0c3f\u0c2f\u0c3e\u0c32\u0c4b\u0c28\u0c47 \u0c05\u0c24\u0c4d\u0c2f\u0c02\u0c24 \u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f\u0c17\u0c3e \u0c2a\u0c47\u0c30\u0c41 \u0c24\u0c46\u0c1a\u0c4d\u0c1a\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28 \u0c35\u0c4d\u0c2f\u0c15\u0c4d\u0c24\u0c3f \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d \u0c07\u0c32\u0c3e \u0c2e\u0c41\u0c17\u0c3f\u0c2f\u0c21\u0c02 \u0c05\u0c2a\u0c4d\u0c2a\u0c1f\u0c4d\u0c32\u0c4b \u0c1a\u0c30\u0c4d\u0c1a\u0c28\u0c40\u0c2f\u0c3e\u0c02\u0c36\u0c2e\u0c48\u0c02\u0c26\u0c3f.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c06\u0c2f\u0c28 \u0c0f\u0c2e\u0c3f \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41?<br>\u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 37 \u0c0f\u0c33\u0c4d\u0c32 \u0c35\u0c2f\u0c38\u0c41\u0c32\u0c4b \u0c09\u0c28\u0c4d\u0c28 \u0c24\u0c41\u0c32\u0c38\u0c3f, \u0c06\u0c30\u0c4d\u0c25\u0c3f\u0c15 \u0c07\u0c2c\u0c4d\u0c2c\u0c02\u0c26\u0c41\u0c32\u0c28\u0c41 \u0c0e\u0c26\u0c41\u0c30\u0c4d\u0c15\u0c4a\u0c02\u0c1f\u0c42\u0c28\u0c47 \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c3e\u0c28\u0c4d\u0c28\u0c3f (Law) \u0c05\u0c2d\u0c4d\u0c2f\u0c38\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c2d\u0c35\u0c3f\u0c37\u0c4d\u0c2f\u0c24\u0c4d\u0c24\u0c41\u0c32\u0c4b \u0c38\u0c4b\u0c32\u0c3f\u0c38\u0c3f\u0c1f\u0c30\u0c4d\u200c\u0c17\u0c3e \u0c38\u0c4d\u0c25\u0c3f\u0c30\u0c2a\u0c21\u0c3e\u0c32\u0c28\u0c3f \u0c06\u0c2f\u0c28 \u0c06\u0c36\u0c3f\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c12\u0c15\u0c2a\u0c4d\u0c2a\u0c41\u0c21\u0c41 &#8216;\u0c38\u0c42\u0c2a\u0c30\u0c4d \u0c1f\u0c40\u0c28\u0c4d&#8217;, &#8216;\u0c2b\u0c3f\u0c1c\u0c3f\u0c15\u0c4d\u0c38\u0c4d \u0c2a\u0c4d\u0c30\u0c3e\u0c21\u0c3f\u0c1c\u0c40&#8217;\u0c17\u0c3e \u0c15\u0c40\u0c30\u0c4d\u0c24\u0c3f\u0c02\u0c1a\u0c2c\u0c21\u0c3f\u0c28 \u0c35\u0c4d\u0c2f\u0c15\u0c4d\u0c24\u0c3f \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c02\u0c32\u0c4b \u0c0e\u0c26\u0c41\u0c30\u0c48\u0c28 \u0c12\u0c21\u0c3f\u0c26\u0c41\u0c21\u0c41\u0c15\u0c41\u0c32\u0c41, \u0c0a\u0c39\u0c3f\u0c02\u0c1a\u0c28\u0c3f \u0c2a\u0c30\u0c3f\u0c38\u0c4d\u0c25\u0c3f\u0c24\u0c41\u0c32\u0c41 \u0c0e\u0c1f\u0c41\u0c35\u0c02\u0c1f\u0c3f\u0c35\u0c48\u0c28\u0c3e \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c15\u0c4a\u0c24\u0c4d\u0c24\u0c17\u0c3e \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c35\u0c1a\u0c4d\u0c1a\u0c28\u0c47\u0c02\u0c26\u0c41\u0c15\u0c41 \u0c06\u0c2f\u0c28 \u0c28\u0c3f\u0c26\u0c30\u0c4d\u0c36\u0c28\u0c02\u0c17\u0c3e \u0c28\u0c3f\u0c32\u0c41\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0c35\u0c4d\u0c2f\u0c15\u0c4d\u0c24\u0c3f\u0c17\u0c24 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c43\u0c24\u0c4d\u0c24\u0c3f\u0c2a\u0c30\u0c2e\u0c48\u0c28 \u0c38\u0c35\u0c3e\u0c33\u0c4d\u0c32\u0c41 \u0c0e\u0c26\u0c41\u0c30\u0c48\u0c28\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c40, \u0c06\u0c2f\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c35\u0c3f\u0c37\u0c2f\u0c15 \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c41 \u0c07\u0c2a\u0c4d\u0c2a\u0c1f\u0c3f\u0c15\u0c40 \u0c0e\u0c02\u0c24\u0c4b \u0c2e\u0c02\u0c26\u0c3f \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c41\u0c32\u0c15\u0c41 \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c28\u0c3f\u0c38\u0c4d\u0c24\u0c42\u0c28\u0c47 \u0c09\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f. \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c02\u0c32\u0c4b \u0c0e\u0c26\u0c41\u0c30\u0c48\u0c28 \u0c35\u0c3f\u0c2a\u0c24\u0c4d\u0c15\u0c30 \u0c2a\u0c30\u0c3f\u0c38\u0c4d\u0c25\u0c3f\u0c24\u0c41\u0c32\u0c28\u0c41 \u0c26\u0c3e\u0c1f\u0c3f, \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3e\u0c26 \u0c35\u0c43\u0c24\u0c4d\u0c24\u0c3f\u0c32\u0c4b \u0c30\u0c3e\u0c23\u0c3f\u0c02\u0c1a\u0c3e\u0c32\u0c28\u0c3f \u0c06\u0c2f\u0c28 \u0c1a\u0c47\u0c38\u0c4d\u0c24\u0c41\u0c28\u0c4d\u0c28 \u0c2a\u0c4d\u0c30\u0c2f\u0c24\u0c4d\u0c28\u0c02 \u0c2a\u0c4d\u0c30\u0c36\u0c02\u0c38\u0c28\u0c40\u0c2f\u0c02.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0c28\u0c4d\u0c2f\u0c42\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40: \u0c1a\u0c3f\u0c28\u0c4d\u0c28\u0c24\u0c28\u0c02\u0c32\u0c4b\u0c28\u0c47 \u0c05\u0c26\u0c4d\u0c2d\u0c41\u0c24\u0c2e\u0c48\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c28\u0c41 \u0c38\u0c3e\u0c27\u0c3f\u0c02\u0c1a\u0c3f, \u0c26\u0c47\u0c36\u0c35\u0c4d\u0c2f\u0c3e\u0c2a\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c05\u0c02\u0c26\u0c30\u0c3f \u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c3f\u0c28\u0c3f \u0c06\u0c15\u0c30\u0c4d\u0c37\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f. 11 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c21\u0c3f\u0c17\u0c4d\u0c30\u0c40, 21 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c2a\u0c40\u0c39\u0c46\u0c1a\u0c4d\u200c\u0c21\u0c40, 22 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c10\u0c10\u0c1f\u0c40 \u0c2a\u0c4d\u0c30\u0c4a\u0c2b\u0c46\u0c38\u0c30\u0c4d.. \u0c07\u0c32\u0c3e \u0c06\u0c2f\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c2a\u0c4d\u0c30\u0c2f\u0c3e\u0c23\u0c02 \u0c0e\u0c02\u0c24\u0c4b \u0c2e\u0c02\u0c26\u0c3f\u0c28\u0c3f \u0c05\u0c2c\u0c4d\u0c2c\u0c41\u0c30\u0c2a\u0c30\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c05\u0c2f\u0c3f\u0c24\u0c47, \u0c26\u0c41\u0c30\u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c35\u0c36\u0c3e\u0c24\u0c4d\u0c24\u0c41 \u0c05\u0c28\u0c3e\u0c30\u0c4b\u0c17\u0c4d\u0c2f \u0c15\u0c3e\u0c30\u0c23\u0c3e\u0c32 \u0c35\u0c32\u0c4d\u0c32 \u0c06\u0c2f\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d\u200c\u0c32\u0c4b \u0c0a\u0c39\u0c3f\u0c02\u0c1a\u0c28\u0c3f \u0c2e\u0c32\u0c41\u0c2a\u0c41\u0c32\u0c41 \u0c1a\u0c4b\u0c1f\u0c41\u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c06\u0c2f\u0c28 \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c02 (Law) \u0c05\u0c2d\u0c4d\u0c2f\u0c38\u0c3f\u0c38\u0c4d\u0c24\u0c42 \u0c15\u0c4a\u0c24\u0c4d\u0c24 \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c47 \u0c2a\u0c4d\u0c30\u0c2f\u0c24\u0c4d\u0c28\u0c02\u0c32\u0c4b \u0c09\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c0e\u0c35\u0c30\u0c40 \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f?1987 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":229108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-229105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politics"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02 - newtelugunews.com\/te<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newtelugunews.com\/te\/\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f-\u0c28\u0c41\u0c02\u0c21\u0c3f-\u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02 - newtelugunews.com\/te\" \/>\n<meta property=\"og:description\" content=\"\u0c28\u0c4d\u0c2f\u0c42\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40: \u0c1a\u0c3f\u0c28\u0c4d\u0c28\u0c24\u0c28\u0c02\u0c32\u0c4b\u0c28\u0c47 \u0c05\u0c26\u0c4d\u0c2d\u0c41\u0c24\u0c2e\u0c48\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c28\u0c41 \u0c38\u0c3e\u0c27\u0c3f\u0c02\u0c1a\u0c3f, \u0c26\u0c47\u0c36\u0c35\u0c4d\u0c2f\u0c3e\u0c2a\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c05\u0c02\u0c26\u0c30\u0c3f \u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c3f\u0c28\u0c3f \u0c06\u0c15\u0c30\u0c4d\u0c37\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f. 11 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c21\u0c3f\u0c17\u0c4d\u0c30\u0c40, 21 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c2a\u0c40\u0c39\u0c46\u0c1a\u0c4d\u200c\u0c21\u0c40, 22 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c10\u0c10\u0c1f\u0c40 \u0c2a\u0c4d\u0c30\u0c4a\u0c2b\u0c46\u0c38\u0c30\u0c4d.. \u0c07\u0c32\u0c3e \u0c06\u0c2f\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c2a\u0c4d\u0c30\u0c2f\u0c3e\u0c23\u0c02 \u0c0e\u0c02\u0c24\u0c4b \u0c2e\u0c02\u0c26\u0c3f\u0c28\u0c3f \u0c05\u0c2c\u0c4d\u0c2c\u0c41\u0c30\u0c2a\u0c30\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c05\u0c2f\u0c3f\u0c24\u0c47, \u0c26\u0c41\u0c30\u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c35\u0c36\u0c3e\u0c24\u0c4d\u0c24\u0c41 \u0c05\u0c28\u0c3e\u0c30\u0c4b\u0c17\u0c4d\u0c2f \u0c15\u0c3e\u0c30\u0c23\u0c3e\u0c32 \u0c35\u0c32\u0c4d\u0c32 \u0c06\u0c2f\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d\u200c\u0c32\u0c4b \u0c0a\u0c39\u0c3f\u0c02\u0c1a\u0c28\u0c3f \u0c2e\u0c32\u0c41\u0c2a\u0c41\u0c32\u0c41 \u0c1a\u0c4b\u0c1f\u0c41\u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c06\u0c2f\u0c28 \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c02 (Law) \u0c05\u0c2d\u0c4d\u0c2f\u0c38\u0c3f\u0c38\u0c4d\u0c24\u0c42 \u0c15\u0c4a\u0c24\u0c4d\u0c24 \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c47 \u0c2a\u0c4d\u0c30\u0c2f\u0c24\u0c4d\u0c28\u0c02\u0c32\u0c4b \u0c09\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c0e\u0c35\u0c30\u0c40 \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f?1987 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newtelugunews.com\/te\/\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f-\u0c28\u0c41\u0c02\u0c21\u0c3f-\u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\/\" \/>\n<meta property=\"og:site_name\" content=\"newtelugunews.com\/te\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/likekottubhayya\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-27T10:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sunilkumar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@newtelugunews\" \/>\n<meta name=\"twitter:site\" content=\"@newtelugunews\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sunilkumar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/\"},\"author\":{\"name\":\"sunilkumar\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#\\\/schema\\\/person\\\/997ccbd25504f2025a581ba473f67dfe\"},\"headline\":\"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02\",\"datePublished\":\"2026-06-27T10:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/newtelugunews.com\\\/te\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/25-587.jpg?fit=600%2C338&ssl=1\",\"articleSection\":[\"politics\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/\",\"url\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/\",\"name\":\"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02 - newtelugunews.com\\\/te\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/newtelugunews.com\\\/te\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/25-587.jpg?fit=600%2C338&ssl=1\",\"datePublished\":\"2026-06-27T10:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/newtelugunews.com\\\/te\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/25-587.jpg?fit=600%2C338&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/newtelugunews.com\\\/te\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/25-587.jpg?fit=600%2C338&ssl=1\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#website\",\"url\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/\",\"name\":\"newtelugunews.com\\\/te\",\"description\":\"telugunews\",\"publisher\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#organization\",\"name\":\"newtelugunews.com\\\/te\",\"url\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/newtelugunews.com\\\/te\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/newtelugunews-logo-copy.png?fit=220%2C77&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/newtelugunews.com\\\/te\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/newtelugunews-logo-copy.png?fit=220%2C77&ssl=1\",\"width\":220,\"height\":77,\"caption\":\"newtelugunews.com\\\/te\"},\"image\":{\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/likekottubhayya\\\/\",\"https:\\\/\\\/x.com\\\/newtelugunews\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/#\\\/schema\\\/person\\\/997ccbd25504f2025a581ba473f67dfe\",\"name\":\"sunilkumar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50fb3c7fca366f115e3f11619493d40f45a5a37384bbcc6317e11dc85d9ae0ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50fb3c7fca366f115e3f11619493d40f45a5a37384bbcc6317e11dc85d9ae0ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50fb3c7fca366f115e3f11619493d40f45a5a37384bbcc6317e11dc85d9ae0ab?s=96&d=mm&r=g\",\"caption\":\"sunilkumar\"},\"url\":\"https:\\\/\\\/newtelugunews.com\\\/te\\\/author\\\/sunilkumar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02 - newtelugunews.com\/te","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newtelugunews.com\/te\/\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f-\u0c28\u0c41\u0c02\u0c21\u0c3f-\u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\/","og_locale":"en_US","og_type":"article","og_title":"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02 - newtelugunews.com\/te","og_description":"\u0c28\u0c4d\u0c2f\u0c42\u0c22\u0c3f\u0c32\u0c4d\u0c32\u0c40: \u0c1a\u0c3f\u0c28\u0c4d\u0c28\u0c24\u0c28\u0c02\u0c32\u0c4b\u0c28\u0c47 \u0c05\u0c26\u0c4d\u0c2d\u0c41\u0c24\u0c2e\u0c48\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c35\u0c3f\u0c1c\u0c2f\u0c3e\u0c32\u0c28\u0c41 \u0c38\u0c3e\u0c27\u0c3f\u0c02\u0c1a\u0c3f, \u0c26\u0c47\u0c36\u0c35\u0c4d\u0c2f\u0c3e\u0c2a\u0c4d\u0c24\u0c02\u0c17\u0c3e \u0c05\u0c02\u0c26\u0c30\u0c3f \u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c3f\u0c28\u0c3f \u0c06\u0c15\u0c30\u0c4d\u0c37\u0c3f\u0c02\u0c1a\u0c3f\u0c28 \u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f. 11 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c21\u0c3f\u0c17\u0c4d\u0c30\u0c40, 21 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c2a\u0c40\u0c39\u0c46\u0c1a\u0c4d\u200c\u0c21\u0c40, 22 \u0c0f\u0c33\u0c4d\u0c32\u0c15\u0c47 \u0c10\u0c10\u0c1f\u0c40 \u0c2a\u0c4d\u0c30\u0c4a\u0c2b\u0c46\u0c38\u0c30\u0c4d.. \u0c07\u0c32\u0c3e \u0c06\u0c2f\u0c28 \u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e \u0c2a\u0c4d\u0c30\u0c2f\u0c3e\u0c23\u0c02 \u0c0e\u0c02\u0c24\u0c4b \u0c2e\u0c02\u0c26\u0c3f\u0c28\u0c3f \u0c05\u0c2c\u0c4d\u0c2c\u0c41\u0c30\u0c2a\u0c30\u0c3f\u0c1a\u0c3f\u0c02\u0c26\u0c3f. \u0c05\u0c2f\u0c3f\u0c24\u0c47, \u0c26\u0c41\u0c30\u0c26\u0c43\u0c37\u0c4d\u0c1f\u0c35\u0c36\u0c3e\u0c24\u0c4d\u0c24\u0c41 \u0c05\u0c28\u0c3e\u0c30\u0c4b\u0c17\u0c4d\u0c2f \u0c15\u0c3e\u0c30\u0c23\u0c3e\u0c32 \u0c35\u0c32\u0c4d\u0c32 \u0c06\u0c2f\u0c28 \u0c15\u0c46\u0c30\u0c40\u0c30\u0c4d\u200c\u0c32\u0c4b \u0c0a\u0c39\u0c3f\u0c02\u0c1a\u0c28\u0c3f \u0c2e\u0c32\u0c41\u0c2a\u0c41\u0c32\u0c41 \u0c1a\u0c4b\u0c1f\u0c41\u0c1a\u0c47\u0c38\u0c41\u0c15\u0c41\u0c28\u0c4d\u0c28\u0c3e\u0c2f\u0c3f. \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c24\u0c41\u0c24\u0c02 \u0c06\u0c2f\u0c28 \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c36\u0c3e\u0c38\u0c4d\u0c24\u0c4d\u0c30\u0c02 (Law) \u0c05\u0c2d\u0c4d\u0c2f\u0c38\u0c3f\u0c38\u0c4d\u0c24\u0c42 \u0c15\u0c4a\u0c24\u0c4d\u0c24 \u0c1c\u0c40\u0c35\u0c3f\u0c24\u0c3e\u0c28\u0c4d\u0c28\u0c3f \u0c2a\u0c4d\u0c30\u0c3e\u0c30\u0c02\u0c2d\u0c3f\u0c02\u0c1a\u0c47 \u0c2a\u0c4d\u0c30\u0c2f\u0c24\u0c4d\u0c28\u0c02\u0c32\u0c4b \u0c09\u0c28\u0c4d\u0c28\u0c3e\u0c30\u0c41. \u0c0e\u0c35\u0c30\u0c40 \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f?1987 [&hellip;]","og_url":"https:\/\/newtelugunews.com\/te\/\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f-\u0c28\u0c41\u0c02\u0c21\u0c3f-\u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\/","og_site_name":"newtelugunews.com\/te","article_publisher":"https:\/\/www.facebook.com\/likekottubhayya\/","article_published_time":"2026-06-27T10:01:00+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1","type":"image\/jpeg"}],"author":"sunilkumar","twitter_card":"summary_large_image","twitter_creator":"@newtelugunews","twitter_site":"@newtelugunews","twitter_misc":{"Written by":"sunilkumar","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#article","isPartOf":{"@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/"},"author":{"name":"sunilkumar","@id":"https:\/\/newtelugunews.com\/te\/#\/schema\/person\/997ccbd25504f2025a581ba473f67dfe"},"headline":"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02","datePublished":"2026-06-27T10:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/newtelugunews.com\/te\/#organization"},"image":{"@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1","articleSection":["politics"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/","url":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/","name":"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02 - newtelugunews.com\/te","isPartOf":{"@id":"https:\/\/newtelugunews.com\/te\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#primaryimage"},"image":{"@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1","datePublished":"2026-06-27T10:01:00+00:00","breadcrumb":{"@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#primaryimage","url":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1","contentUrl":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/newtelugunews.com\/te\/%e0%b0%ac%e0%b0%be%e0%b0%b2%e0%b0%ae%e0%b1%87%e0%b0%a7%e0%b0%be%e0%b0%b5%e0%b0%bf-%e0%b0%a8%e0%b1%81%e0%b0%82%e0%b0%a1%e0%b0%bf-%e0%b0%a8%e0%b1%8d%e0%b0%af%e0%b0%be%e0%b0%af%e0%b0%b5%e0%b0%bf%e0%b0%a6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newtelugunews.com\/te\/"},{"@type":"ListItem","position":2,"name":"\u0c2c\u0c3e\u0c32\u0c2e\u0c47\u0c27\u0c3e\u0c35\u0c3f \u0c28\u0c41\u0c02\u0c21\u0c3f \u0c28\u0c4d\u0c2f\u0c3e\u0c2f\u0c35\u0c3f\u0c26\u0c4d\u0c2f\u0c3e\u0c30\u0c4d\u0c25\u0c3f\u0c17\u0c3e.. \u0c24\u0c25\u0c3e\u0c17\u0c24 \u0c05\u0c35\u0c24\u0c3e\u0c30\u0c4d \u0c24\u0c41\u0c32\u0c38\u0c3f \u0c38\u0c4d\u0c2b\u0c42\u0c30\u0c4d\u0c24\u0c3f\u0c26\u0c3e\u0c2f\u0c15 \u0c2e\u0c30\u0c3f\u0c2f\u0c41 \u0c35\u0c3f\u0c37\u0c3e\u0c26 \u0c2a\u0c4d\u0c30\u0c38\u0c4d\u0c25\u0c3e\u0c28\u0c02"}]},{"@type":"WebSite","@id":"https:\/\/newtelugunews.com\/te\/#website","url":"https:\/\/newtelugunews.com\/te\/","name":"newtelugunews.com\/te","description":"telugunews","publisher":{"@id":"https:\/\/newtelugunews.com\/te\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newtelugunews.com\/te\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/newtelugunews.com\/te\/#organization","name":"newtelugunews.com\/te","url":"https:\/\/newtelugunews.com\/te\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/newtelugunews.com\/te\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2023\/02\/newtelugunews-logo-copy.png?fit=220%2C77&ssl=1","contentUrl":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2023\/02\/newtelugunews-logo-copy.png?fit=220%2C77&ssl=1","width":220,"height":77,"caption":"newtelugunews.com\/te"},"image":{"@id":"https:\/\/newtelugunews.com\/te\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/likekottubhayya\/","https:\/\/x.com\/newtelugunews"]},{"@type":"Person","@id":"https:\/\/newtelugunews.com\/te\/#\/schema\/person\/997ccbd25504f2025a581ba473f67dfe","name":"sunilkumar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/50fb3c7fca366f115e3f11619493d40f45a5a37384bbcc6317e11dc85d9ae0ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50fb3c7fca366f115e3f11619493d40f45a5a37384bbcc6317e11dc85d9ae0ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50fb3c7fca366f115e3f11619493d40f45a5a37384bbcc6317e11dc85d9ae0ab?s=96&d=mm&r=g","caption":"sunilkumar"},"url":"https:\/\/newtelugunews.com\/te\/author\/sunilkumar\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/newtelugunews.com\/te\/wp-content\/uploads\/2026\/06\/25-587.jpg?fit=600%2C338&ssl=1","_links":{"self":[{"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/posts\/229105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/comments?post=229105"}],"version-history":[{"count":1,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/posts\/229105\/revisions"}],"predecessor-version":[{"id":229109,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/posts\/229105\/revisions\/229109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/media\/229108"}],"wp:attachment":[{"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/media?parent=229105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/categories?post=229105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newtelugunews.com\/te\/wp-json\/wp\/v2\/tags?post=229105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}